{"id":12732,"count":1,"description":"","link":"https:\/\/www.buylandingpagedesign.com\/blog\/tag\/sales-funnel-landing-page-design-for-appliance-repair\/","name":"sales funnel landing page design for appliance repair","slug":"sales-funnel-landing-page-design-for-appliance-repair","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.buylandingpagedesign.com\/blog\/wp-json\/wp\/v2\/tags\/12732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buylandingpagedesign.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.buylandingpagedesign.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.buylandingpagedesign.com\/blog\/wp-json\/wp\/v2\/posts?tags=12732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}