{"id":12058,"count":1,"description":"","link":"https:\/\/www.buylandingpagedesign.com\/blog\/tag\/sales-funnel-law-landing-page\/","name":"sales funnel law landing page","slug":"sales-funnel-law-landing-page","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.buylandingpagedesign.com\/blog\/wp-json\/wp\/v2\/tags\/12058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buylandingpagedesign.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.buylandingpagedesign.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.buylandingpagedesign.com\/blog\/wp-json\/wp\/v2\/posts?tags=12058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}